{"id":1901,"date":"2021-07-07T18:02:33","date_gmt":"2021-07-07T16:02:33","guid":{"rendered":"https:\/\/collabfactory.art\/uncategorized\/definition-art-numerique-et-nft\/"},"modified":"2021-07-19T14:52:05","modified_gmt":"2021-07-19T12:52:05","slug":"digital-art-and-nft-definition","status":"publish","type":"post","link":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/","title":{"rendered":"Digital art and NFTs finally explained!"},"content":{"rendered":"\n<p>$ 69 million is the price of the digital artwork by artist Beeple sold by Christie&#8217;s on March 11: no more doubt, digital is indeed at the heart of the art market today.<\/p>\n\n\n\n<p>Blockchain, AI, VR, NFT &#8230; The vocabulary between acronym and Anglicism is enough to discourage those who want to be directly or indirectly interested in new technologies, and the art world is no exception.<\/p>\n\n\n\n<p>Collab Factory explains everything to you.<\/p>\n\n\n\n<p>While digital art has been part of the common imagination for several years now, its market has just taken a radical turn in terms of its reliability.<\/p>\n\n\n\n<p>Long singled out for their lack of traceability and authenticity, digital works of art, intangible and existing online only, may have found the missing link in their economic development.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mk0collabfactordxxd6.kinstacdn.com\/wp-content\/uploads\/2021\/07\/000_94P6YB-1024x576.jpeg\" alt=\"\" class=\"wp-image-1525\" width=\"613\" height=\"344\" srcset=\"https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/000_94P6YB-1024x576.jpeg 1024w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/000_94P6YB-300x169.jpeg 300w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/000_94P6YB-768x432.jpeg 768w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/000_94P6YB.jpeg 1280w\" sizes=\"auto, (max-width: 613px) 100vw, 613px\" \/><figcaption>Everydays: the first 5000 days &#8211; \u00a9 Beeple<br><\/figcaption><\/figure><\/div>\n\n\n\n<p>With blockchain technologies (protected online database) and NFT (non-fungible token : ultra-secure original digital object) a digital work of art is now as fixed and protected as the Mona Lisa at the Louvre ; Mona Lisa can be photographed, copied, but the original work will remain in the museum. The same is now true for digital works: if they can be distributed indefinitely online, the ownership of the original version will remain that of a single entity thanks to these non-fungible tokens.<\/p>\n\n\n\n<p>This dynamic is part of the continuity of the abolition of borders for art. We now speak of &#8220;crypto art&#8221; to qualify an intangible but secure work. If this new approach may raise questions, the appearance of artists in these new technologies is however encouraging. Indeed, artists use these new media to question them and try to bring a new perspective to their use. While nothing proves that NFT and blockchain tools will establish themselves in the long term, their safety has now been proven. Democratizing their practice is now within everyone&#8217;s reach.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/collabfactory.art\/en\/realisations\/social-media-en\/mastercard-x-les-folies-passageres\/\">Check out our 100% digital campaigns<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Digital art, only in auction rooms?<\/strong><\/p>\n\n\n\n<p>Christies has already taken a stand in its auction process, but what about the related functions of this field of artistic expression?<\/p>\n\n\n\n<p>Exhibitions featuring digital art in their journey have boomed in recent years and we observe a collusion between tangible and intangible work that gives a new dimension to the experience of visitors.<\/p>\n\n\n\n<p>In addition, establishments forced to close their doors in recent months have redoubled their efforts to develop these new technologies so that, finally, &#8220;culture comes to you&#8221;.<\/p>\n\n\n\n<p id=\"yui_3_17_2_1_1626698718549_537\">These new practices do not stop at the primary and secondary art markets but are intended to spread everywhere and especially where we do not expect them: a new wave of artists is emerging, whom we are following closely at Collab Factory. .<\/p>\n\n\n\n<p>Virtual reality therefore poses fewer and fewer technical problems, augmented reality is exploding and brands are seizing it &#8230; Now that the market is ready, perhaps it is time to reinject some content and meaning. And isn&#8217;t that the role of an artist precisely &#8230;?<\/p>\n\n\n\n<p>At Collab Factory, we place our expertise at the service of your brand to imagine new, more artistic digital strategies, in particular by teaming up with this new generation of digital artists. Proof in pictures? Find our 100% digital campaign for Mastercard <a href=\"https:\/\/collabfactory.art\/en\/realisations\/social-media-en\/mastercard-x-les-folies-passageres\/\">here<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"319\" src=\"https:\/\/mk0collabfactordxxd6.kinstacdn.com\/wp-content\/uploads\/2021\/07\/mastercard-1024x319.png\" alt=\"\" class=\"wp-image-1527\" srcset=\"https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/mastercard-1024x319.png 1024w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/mastercard-300x93.png 300w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/mastercard-768x239.png 768w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/mastercard-1536x478.png 1536w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/mastercard-1366x425.png 1366w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/mastercard.png 1572w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Une oeuvre de Maud Bergeron 100% en ligne pour Mastercard France &#8211; \u00a9 Collab Factory<\/figcaption><\/figure>\n\n\n\n<p><strong>Other examples<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mk0collabfactordxxd6.kinstacdn.com\/wp-content\/uploads\/2021\/07\/Capturede\u0301cran2021-03-31a\u030010.53.32-1024x226.png\" alt=\"\" class=\"wp-image-1529\" width=\"854\" height=\"188\" srcset=\"https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/Capturede\u0301cran2021-03-31a\u030010.53.32-1024x226.png 1024w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/Capturede\u0301cran2021-03-31a\u030010.53.32-300x66.png 300w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/Capturede\u0301cran2021-03-31a\u030010.53.32-768x170.png 768w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/Capturede\u0301cran2021-03-31a\u030010.53.32-1536x339.png 1536w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/Capturede\u0301cran2021-03-31a\u030010.53.32-1366x302.png 1366w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/Capturede\u0301cran2021-03-31a\u030010.53.32.png 1920w\" sizes=\"auto, (max-width: 854px) 100vw, 854px\" \/><figcaption>Mithridate LFW 2021 x Dejha Ti &amp; Ania Catherine<br>Pop-up site for the launch of a new collection designed by artists &#8211; \u00a9 MTart<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/mk0collabfactordxxd6.kinstacdn.com\/wp-content\/uploads\/2021\/07\/C0IwIdoWgAIQEk6-1024x683.jpeg\" alt=\"\" class=\"wp-image-1531\" srcset=\"https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/C0IwIdoWgAIQEk6-1024x683.jpeg 1024w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/C0IwIdoWgAIQEk6-300x200.jpeg 300w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/C0IwIdoWgAIQEk6-768x512.jpeg 768w, https:\/\/collabfactory.art\/wp-content\/uploads\/2021\/07\/C0IwIdoWgAIQEk6.jpeg 1342w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>LCL x Quayola, Digital mural in the headquarters &#8211; \u00a9 LCL<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>$ 69 million is the price of the digital artwork by artist Beeple sold by Christie&#8217;s on March 11: no more doubt, digital is indeed at the heart of the art market today. Blockchain, AI, VR, NFT &#8230; The vocabulary between acronym and Anglicism is enough to discourage those who want to be directly or [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-1901","post","type-post","status-publish","format-standard","hentry","category-article"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digital art and NFTs finally explained! - Collab Factory -<\/title>\n<meta name=\"description\" content=\"What is a NFT ? IA ? Blockhain ? Digital art ? Collab Factory explains you everything\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digital art and NFTs finally explained! - Collab Factory -\" \/>\n<meta property=\"og:description\" content=\"What is a NFT ? IA ? Blockhain ? Digital art ? Collab Factory explains you everything\" \/>\n<meta property=\"og:url\" content=\"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/\" \/>\n<meta property=\"og:site_name\" content=\"Collab Factory | Collaborations Artistiques (Marque x Artiste)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/collabfactory.art\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-07T16:02:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-19T12:52:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mk0collabfactordxxd6.kinstacdn.com\/wp-content\/uploads\/2021\/07\/000_94P6YB-1024x576.jpeg\" \/>\n<meta name=\"author\" content=\"collabfactory\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"collabfactory\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/\"},\"author\":{\"name\":\"collabfactory\",\"@id\":\"https:\\\/\\\/collabfactory.art\\\/#\\\/schema\\\/person\\\/f7ddc66d7d17a60057d61d6bacc638e2\"},\"headline\":\"Digital art and NFTs finally explained!\",\"datePublished\":\"2021-07-07T16:02:33+00:00\",\"dateModified\":\"2021-07-19T12:52:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/\"},\"wordCount\":578,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/collabfactory.art\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mk0collabfactordxxd6.kinstacdn.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/000_94P6YB-1024x576.jpeg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/\",\"url\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/\",\"name\":\"Digital art and NFTs finally explained! - Collab Factory -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/collabfactory.art\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mk0collabfactordxxd6.kinstacdn.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/000_94P6YB-1024x576.jpeg\",\"datePublished\":\"2021-07-07T16:02:33+00:00\",\"dateModified\":\"2021-07-19T12:52:05+00:00\",\"description\":\"What is a NFT ? IA ? Blockhain ? Digital art ? Collab Factory explains you everything\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mk0collabfactordxxd6.kinstacdn.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/000_94P6YB-1024x576.jpeg\",\"contentUrl\":\"https:\\\/\\\/mk0collabfactordxxd6.kinstacdn.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/000_94P6YB-1024x576.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/article\\\/digital-art-and-nft-definition\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digital art and NFTs finally explained!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/collabfactory.art\\\/#website\",\"url\":\"https:\\\/\\\/collabfactory.art\\\/\",\"name\":\"Collab Factory | Collaborations Artistiques (Marque x Artiste)\",\"description\":\"Agence de collaborations artistiques entre Marques et Artistes. Cr\u00e9ation d&#039;\u00e9ditions limit\u00e9es, de fresques, de performances live et d&#039;ateliers. Street Art et Art Contemporain. Fondatrice : Mathilde Mazuranic\",\"publisher\":{\"@id\":\"https:\\\/\\\/collabfactory.art\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/collabfactory.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/collabfactory.art\\\/#organization\",\"name\":\"Collab Factory\",\"url\":\"https:\\\/\\\/collabfactory.art\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/collabfactory.art\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/collabfactory.art\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo.png\",\"contentUrl\":\"http:\\\/\\\/collabfactory.art\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo.png\",\"width\":1100,\"height\":649,\"caption\":\"Collab Factory\"},\"image\":{\"@id\":\"https:\\\/\\\/collabfactory.art\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/collabfactory.art\",\"https:\\\/\\\/www.instagram.com\\\/collabfactory.art\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/collab-factory\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/collabfactory.art\\\/#\\\/schema\\\/person\\\/f7ddc66d7d17a60057d61d6bacc638e2\",\"name\":\"collabfactory\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce1aabcf6503cfefcab951f5157d68e32713fedfb5dfd3e5051007a435a687da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce1aabcf6503cfefcab951f5157d68e32713fedfb5dfd3e5051007a435a687da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce1aabcf6503cfefcab951f5157d68e32713fedfb5dfd3e5051007a435a687da?s=96&d=mm&r=g\",\"caption\":\"collabfactory\"},\"url\":\"https:\\\/\\\/collabfactory.art\\\/en\\\/author\\\/collabfactory\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digital art and NFTs finally explained! - Collab Factory -","description":"What is a NFT ? IA ? Blockhain ? Digital art ? Collab Factory explains you everything","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/","og_locale":"en_US","og_type":"article","og_title":"Digital art and NFTs finally explained! - Collab Factory -","og_description":"What is a NFT ? IA ? Blockhain ? Digital art ? Collab Factory explains you everything","og_url":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/","og_site_name":"Collab Factory | Collaborations Artistiques (Marque x Artiste)","article_publisher":"https:\/\/www.facebook.com\/collabfactory.art","article_published_time":"2021-07-07T16:02:33+00:00","article_modified_time":"2021-07-19T12:52:05+00:00","og_image":[{"url":"https:\/\/mk0collabfactordxxd6.kinstacdn.com\/wp-content\/uploads\/2021\/07\/000_94P6YB-1024x576.jpeg","type":"","width":"","height":""}],"author":"collabfactory","twitter_card":"summary_large_image","twitter_misc":{"Written by":"collabfactory","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/#article","isPartOf":{"@id":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/"},"author":{"name":"collabfactory","@id":"https:\/\/collabfactory.art\/#\/schema\/person\/f7ddc66d7d17a60057d61d6bacc638e2"},"headline":"Digital art and NFTs finally explained!","datePublished":"2021-07-07T16:02:33+00:00","dateModified":"2021-07-19T12:52:05+00:00","mainEntityOfPage":{"@id":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/"},"wordCount":578,"commentCount":0,"publisher":{"@id":"https:\/\/collabfactory.art\/#organization"},"image":{"@id":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/#primaryimage"},"thumbnailUrl":"https:\/\/mk0collabfactordxxd6.kinstacdn.com\/wp-content\/uploads\/2021\/07\/000_94P6YB-1024x576.jpeg","articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/","url":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/","name":"Digital art and NFTs finally explained! - Collab Factory -","isPartOf":{"@id":"https:\/\/collabfactory.art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/#primaryimage"},"image":{"@id":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/#primaryimage"},"thumbnailUrl":"https:\/\/mk0collabfactordxxd6.kinstacdn.com\/wp-content\/uploads\/2021\/07\/000_94P6YB-1024x576.jpeg","datePublished":"2021-07-07T16:02:33+00:00","dateModified":"2021-07-19T12:52:05+00:00","description":"What is a NFT ? IA ? Blockhain ? Digital art ? Collab Factory explains you everything","breadcrumb":{"@id":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/#primaryimage","url":"https:\/\/mk0collabfactordxxd6.kinstacdn.com\/wp-content\/uploads\/2021\/07\/000_94P6YB-1024x576.jpeg","contentUrl":"https:\/\/mk0collabfactordxxd6.kinstacdn.com\/wp-content\/uploads\/2021\/07\/000_94P6YB-1024x576.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/collabfactory.art\/en\/article\/digital-art-and-nft-definition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/collabfactory.art\/en\/"},{"@type":"ListItem","position":2,"name":"Digital art and NFTs finally explained!"}]},{"@type":"WebSite","@id":"https:\/\/collabfactory.art\/#website","url":"https:\/\/collabfactory.art\/","name":"Collab Factory | Collaborations Artistiques (Marque x Artiste)","description":"Agence de collaborations artistiques entre Marques et Artistes. Cr\u00e9ation d&#039;\u00e9ditions limit\u00e9es, de fresques, de performances live et d&#039;ateliers. Street Art et Art Contemporain. Fondatrice : Mathilde Mazuranic","publisher":{"@id":"https:\/\/collabfactory.art\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/collabfactory.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/collabfactory.art\/#organization","name":"Collab Factory","url":"https:\/\/collabfactory.art\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/collabfactory.art\/#\/schema\/logo\/image\/","url":"http:\/\/collabfactory.art\/wp-content\/uploads\/2021\/06\/logo.png","contentUrl":"http:\/\/collabfactory.art\/wp-content\/uploads\/2021\/06\/logo.png","width":1100,"height":649,"caption":"Collab Factory"},"image":{"@id":"https:\/\/collabfactory.art\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/collabfactory.art","https:\/\/www.instagram.com\/collabfactory.art\/","https:\/\/www.linkedin.com\/company\/collab-factory\/"]},{"@type":"Person","@id":"https:\/\/collabfactory.art\/#\/schema\/person\/f7ddc66d7d17a60057d61d6bacc638e2","name":"collabfactory","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ce1aabcf6503cfefcab951f5157d68e32713fedfb5dfd3e5051007a435a687da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce1aabcf6503cfefcab951f5157d68e32713fedfb5dfd3e5051007a435a687da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce1aabcf6503cfefcab951f5157d68e32713fedfb5dfd3e5051007a435a687da?s=96&d=mm&r=g","caption":"collabfactory"},"url":"https:\/\/collabfactory.art\/en\/author\/collabfactory\/"}]}},"_links":{"self":[{"href":"https:\/\/collabfactory.art\/en\/wp-json\/wp\/v2\/posts\/1901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collabfactory.art\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/collabfactory.art\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/collabfactory.art\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/collabfactory.art\/en\/wp-json\/wp\/v2\/comments?post=1901"}],"version-history":[{"count":3,"href":"https:\/\/collabfactory.art\/en\/wp-json\/wp\/v2\/posts\/1901\/revisions"}],"predecessor-version":[{"id":1936,"href":"https:\/\/collabfactory.art\/en\/wp-json\/wp\/v2\/posts\/1901\/revisions\/1936"}],"wp:attachment":[{"href":"https:\/\/collabfactory.art\/en\/wp-json\/wp\/v2\/media?parent=1901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/collabfactory.art\/en\/wp-json\/wp\/v2\/categories?post=1901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/collabfactory.art\/en\/wp-json\/wp\/v2\/tags?post=1901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}